{"id":7923,"date":"2025-12-02T13:57:06","date_gmt":"2025-12-02T12:57:06","guid":{"rendered":"https:\/\/www.visitclusone.it\/?post_type=ospitalita&#038;p=7923"},"modified":"2025-12-02T14:31:15","modified_gmt":"2025-12-02T13:31:15","slug":"casa-via-ger","status":"publish","type":"ospitalita","link":"https:\/\/www.visitclusone.it\/en\/ospitalita\/casa-via-ger\/","title":{"rendered":"Casa Via Ger"},"content":{"rendered":"<p data-start=\"266\" data-end=\"426\"><strong data-start=\"266\" data-end=\"282\">Casa Via Ger<\/strong> \u00e8 un appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.<\/p>\n<p data-start=\"428\" data-end=\"718\">Completamente ristrutturato nel 2025, l\u2019alloggio dispone di una luminosa zona giorno con angolo cottura attrezzato, un bagno con doccia e una camera matrimoniale. L\u2019arredamento moderno si combina con il calore delle pareti rivestite in legno, creando un ambiente accogliente e confortevole.<\/p>\n<p data-start=\"720\" data-end=\"854\">La casa \u00e8 circondata da un ampio giardino condiviso con i proprietari, dove \u00e8 possibile vedere cavalli, cani, gatti, pecore e conigli.<\/p>\n<p data-start=\"856\" data-end=\"881\">Gli animali sono ammessi.<\/p>\n","protected":false},"featured_media":7930,"parent":0,"template":"","categorie_ospitalita":[191],"class_list":["post-7923","ospitalita","type-ospitalita","status-publish","has-post-thumbnail","hentry","categorie_ospitalita-affitti-locazioni-turistiche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa Via Ger - Clusone (BG)<\/title>\n<meta name=\"description\" content=\"appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Via Ger - Clusone (BG)\" \/>\n<meta property=\"og:description\" content=\"appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Clusone\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-02T13:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2025\/12\/CASA-VIA-GER-copertina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/\",\"url\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/\",\"name\":\"Casa Via Ger - Clusone (BG)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitclusone.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CASA-VIA-GER-copertina.jpg\",\"datePublished\":\"2025-12-02T12:57:06+00:00\",\"dateModified\":\"2025-12-02T13:31:15+00:00\",\"description\":\"appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitclusone.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CASA-VIA-GER-copertina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitclusone.it\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CASA-VIA-GER-copertina.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"CASA VIA GER Copertina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/casa-via-ger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ospitalit\u00e0\",\"item\":\"https:\\\/\\\/www.visitclusone.it\\\/ospitalita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa Via Ger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/#website\",\"url\":\"https:\\\/\\\/www.visitclusone.it\\\/\",\"name\":\"Visit Clusone\",\"description\":\"Conosci, esplora, scopri Clusone\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitclusone.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Via Ger - Clusone (BG)","description":"appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/","og_locale":"en_US","og_type":"article","og_title":"Casa Via Ger - Clusone (BG)","og_description":"appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.","og_url":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/","og_site_name":"Visit Clusone","article_modified_time":"2025-12-02T13:31:15+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2025\/12\/CASA-VIA-GER-copertina.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/","url":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/","name":"Casa Via Ger - Clusone (BG)","isPartOf":{"@id":"https:\/\/www.visitclusone.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/#primaryimage"},"image":{"@id":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2025\/12\/CASA-VIA-GER-copertina.jpg","datePublished":"2025-12-02T12:57:06+00:00","dateModified":"2025-12-02T13:31:15+00:00","description":"appartamento con ingresso indipendente, situato a poca distanza dal centro storico di Clusone, in una zona tranquilla e immersa nel verde.","breadcrumb":{"@id":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/#primaryimage","url":"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2025\/12\/CASA-VIA-GER-copertina.jpg","contentUrl":"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2025\/12\/CASA-VIA-GER-copertina.jpg","width":1500,"height":1000,"caption":"CASA VIA GER Copertina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitclusone.it\/ospitalita\/casa-via-ger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ospitalit\u00e0","item":"https:\/\/www.visitclusone.it\/ospitalita\/"},{"@type":"ListItem","position":2,"name":"Casa Via Ger"}]},{"@type":"WebSite","@id":"https:\/\/www.visitclusone.it\/#website","url":"https:\/\/www.visitclusone.it\/","name":"Visit Clusone","description":"Conosci, esplora, scopri Clusone","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitclusone.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/ospitalita\/7923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/ospitalita"}],"about":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/types\/ospitalita"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/media\/7930"}],"wp:attachment":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/media?parent=7923"}],"wp:term":[{"taxonomy":"categorie_ospitalita","embeddable":true,"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/categorie_ospitalita?post=7923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}