{"id":1401,"date":"2021-07-29T08:52:57","date_gmt":"2021-07-29T06:52:57","guid":{"rendered":"https:\/\/www.visitclusone.it\/home\/"},"modified":"2022-07-14T09:56:33","modified_gmt":"2022-07-14T07:56:33","slug":"home","status":"publish","type":"page","link":"https:\/\/www.visitclusone.it\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<h1 style=\"text-align: center;\">\u00a0Explore and discover Clusone<\/h1>\n<h1 style=\"text-align: center;\">#VisitClusone<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Explore and discover Clusone #VisitClusone<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"index.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1401","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visit Clusone - Conosci, esplora, scopri Clusone<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell&#039;altopiano orobico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitclusone.it\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visit Clusone - Conosci, esplora, scopri Clusone\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell&#039;altopiano orobico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitclusone.it\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Clusone\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-14T07:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2021\/08\/piazza-orologio-clusone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Visit Clusone - Conosci, esplora, scopri Clusone\" \/>\n<meta name=\"twitter:description\" content=\"Scopri l&#039;offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell&#039;altopiano orobico.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2021\/08\/piazza-orologio-clusone.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/en\\\/\",\"url\":\"https:\\\/\\\/www.visitclusone.it\\\/en\\\/\",\"name\":\"Visit Clusone - Conosci, esplora, scopri Clusone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/#website\"},\"datePublished\":\"2021-07-29T06:52:57+00:00\",\"dateModified\":\"2022-07-14T07:56:33+00:00\",\"description\":\"Scopri l'offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell'altopiano orobico.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitclusone.it\\\/en\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitclusone.it\\\/#website\",\"url\":\"https:\\\/\\\/www.visitclusone.it\\\/\",\"name\":\"Visit Clusone\",\"description\":\"Conosci, esplora, scopri Clusone\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitclusone.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visit Clusone - Conosci, esplora, scopri Clusone","description":"Scopri l'offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell'altopiano orobico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitclusone.it\/en\/","og_locale":"en_US","og_type":"article","og_title":"Visit Clusone - Conosci, esplora, scopri Clusone","og_description":"Scopri l'offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell'altopiano orobico.","og_url":"https:\/\/www.visitclusone.it\/en\/","og_site_name":"Visit Clusone","article_modified_time":"2022-07-14T07:56:33+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2021\/08\/piazza-orologio-clusone.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Visit Clusone - Conosci, esplora, scopri Clusone","twitter_description":"Scopri l'offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell'altopiano orobico.","twitter_image":"https:\/\/www.visitclusone.it\/wp-content\/uploads\/2021\/08\/piazza-orologio-clusone.jpg","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visitclusone.it\/en\/","url":"https:\/\/www.visitclusone.it\/en\/","name":"Visit Clusone - Conosci, esplora, scopri Clusone","isPartOf":{"@id":"https:\/\/www.visitclusone.it\/#website"},"datePublished":"2021-07-29T06:52:57+00:00","dateModified":"2022-07-14T07:56:33+00:00","description":"Scopri l'offerta turistica della citt\u00e0 di Clusone e vivi una vacanza indimenticabile nel cuore dell'altopiano orobico.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitclusone.it\/en\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.visitclusone.it\/#website","url":"https:\/\/www.visitclusone.it\/","name":"Visit Clusone","description":"Conosci, esplora, scopri Clusone","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitclusone.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/pages\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":3,"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/pages\/1401\/revisions"}],"predecessor-version":[{"id":1404,"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/pages\/1401\/revisions\/1404"}],"wp:attachment":[{"href":"https:\/\/www.visitclusone.it\/en\/wp-json\/wp\/v2\/media?parent=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}